{"id":100566,"date":"2019-05-16T00:00:00","date_gmt":"2019-05-16T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/pince-coupante-5-1-4-2\/"},"modified":"2022-04-18T11:49:43","modified_gmt":"2022-04-18T15:49:43","slug":"pince-coupante-5-1-4-2","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/","title":{"rendered":"HT-222 \u2013 5-1\/4&#8221; Cutter"},"content":{"rendered":"<h2>Pince coupante 5-1\/4&#8243; \u2013 HT-222<\/h2>\n<p>Pince coupante 5-14\/&#8221; pour coupe de finition. Les pinces peuvent couper jusqu&#8217;\u00e0 18 AWG.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pince coupante 5-1\/4&#8243; \u2013 HT-222 Pince coupante 5-14\/&#8221; pour coupe de finition. Les pinces peuvent couper jusqu&#8217;\u00e0 18 AWG. &nbsp;<\/p>\n","protected":false},"featured_media":23078,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11581,11550],"product_tag":[11917],"class_list":["post-100566","product","type-product","status-publish","has-post-thumbnail","product_cat-pliers","product_cat-tools","product_tag-pliers-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":384,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HT-222 \u2013 5-1\/4&#039;&#039; Cutter - Add-Tronique<\/title>\n<meta name=\"description\" content=\"HT-222 \u2013 5-1\/4&#039;&#039; Cutter Cutting pliers 5-1\/4&#039;&#039; for finishing cut. Cuts up to 18 AWG\/lead\/1mm copper\/soft metal wires\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HT-222 \u2013 5-1\/4&#039;&#039; Cutter - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"HT-222 \u2013 5-1\/4&#039;&#039; Cutter Cutting pliers 5-1\/4&#039;&#039; for finishing cut. Cuts up to 18 AWG\/lead\/1mm copper\/soft metal wires\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T15:49:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2018\/10\/613004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/pliers\\\/pince-coupante-5-1-4-2\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/pliers\\\/pince-coupante-5-1-4-2\\\/\",\"name\":\"HT-222 \u2013 5-1\\\/4'' Cutter - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/pliers\\\/pince-coupante-5-1-4-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/pliers\\\/pince-coupante-5-1-4-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/613004.jpg\",\"datePublished\":\"2019-05-16T04:00:00+00:00\",\"dateModified\":\"2022-04-18T15:49:43+00:00\",\"description\":\"HT-222 \u2013 5-1\\\/4'' Cutter Cutting pliers 5-1\\\/4'' for finishing cut. Cuts up to 18 AWG\\\/lead\\\/1mm copper\\\/soft metal wires\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/pliers\\\/pince-coupante-5-1-4-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/pliers\\\/pince-coupante-5-1-4-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/pliers\\\/pince-coupante-5-1-4-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/613004.jpg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/613004.jpg\",\"width\":300,\"height\":300,\"caption\":\"HT-222 \u2013 5-1\\\/4'' Cutter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/pliers\\\/pince-coupante-5-1-4-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HT-222 \u2013 5-1\\\/4&#8221; Cutter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HT-222 \u2013 5-1\/4'' Cutter - Add-Tronique","description":"HT-222 \u2013 5-1\/4'' Cutter Cutting pliers 5-1\/4'' for finishing cut. Cuts up to 18 AWG\/lead\/1mm copper\/soft metal wires","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/","og_locale":"en_US","og_type":"article","og_title":"HT-222 \u2013 5-1\/4'' Cutter - Add-Tronique","og_description":"HT-222 \u2013 5-1\/4'' Cutter Cutting pliers 5-1\/4'' for finishing cut. Cuts up to 18 AWG\/lead\/1mm copper\/soft metal wires","og_url":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T15:49:43+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2018\/10\/613004.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/","url":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/","name":"HT-222 \u2013 5-1\/4'' Cutter - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2018\/10\/613004.jpg","datePublished":"2019-05-16T04:00:00+00:00","dateModified":"2022-04-18T15:49:43+00:00","description":"HT-222 \u2013 5-1\/4'' Cutter Cutting pliers 5-1\/4'' for finishing cut. Cuts up to 18 AWG\/lead\/1mm copper\/soft metal wires","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2018\/10\/613004.jpg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2018\/10\/613004.jpg","width":300,"height":300,"caption":"HT-222 \u2013 5-1\/4'' Cutter"},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/pliers\/pince-coupante-5-1-4-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"HT-222 \u2013 5-1\/4&#8221; Cutter"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/100566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=100566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/23078"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=100566"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=100566"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=100566"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=100566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}