{"id":101719,"date":"2018-10-25T00:00:00","date_gmt":"2018-10-25T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/afw16-16-4-seasons-wiper-blade\/"},"modified":"2022-04-18T12:09:15","modified_gmt":"2022-04-18T16:09:15","slug":"afw16-16-4-seasons-wiper-blade","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/","title":{"rendered":"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade"},"content":{"rendered":"<h2>AFW16 \u2013\u00a0 16 \u201d 4 Seasons Wiper Blade<\/h2>\n<ul>\n<li>Graphite Coated<\/li>\n<li>Multi-adaptor<\/li>\n<li>Easy Installation<\/li>\n<li>Use 4 seasons<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>AFW16 \u2013\u00a0 16 \u201d 4 Seasons Wiper Blade Graphite Coated Multi-adaptor Easy Installation Use 4 seasons<\/p>\n","protected":false},"featured_media":68781,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11113,13410],"product_tag":[],"class_list":["post-101719","product","type-product","status-publish","has-post-thumbnail","product_cat-cars-and-boats","product_cat-wipers","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":12,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade - Add-Tronique<\/title>\n<meta name=\"description\" content=\"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade \u2013 more sizes available online and in store\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade \u2013 more sizes available online and in store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T16:09:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/afw16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cars-and-boats\\\/wipers\\\/afw16-16-4-seasons-wiper-blade\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cars-and-boats\\\/wipers\\\/afw16-16-4-seasons-wiper-blade\\\/\",\"name\":\"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cars-and-boats\\\/wipers\\\/afw16-16-4-seasons-wiper-blade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cars-and-boats\\\/wipers\\\/afw16-16-4-seasons-wiper-blade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/afw16.jpg\",\"datePublished\":\"2018-10-25T04:00:00+00:00\",\"dateModified\":\"2022-04-18T16:09:15+00:00\",\"description\":\"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade \u2013 more sizes available online and in store\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cars-and-boats\\\/wipers\\\/afw16-16-4-seasons-wiper-blade\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cars-and-boats\\\/wipers\\\/afw16-16-4-seasons-wiper-blade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cars-and-boats\\\/wipers\\\/afw16-16-4-seasons-wiper-blade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/afw16.jpg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/afw16.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cars-and-boats\\\/wipers\\\/afw16-16-4-seasons-wiper-blade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade - Add-Tronique","description":"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade \u2013 more sizes available online and in store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/","og_locale":"en_US","og_type":"article","og_title":"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade - Add-Tronique","og_description":"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade \u2013 more sizes available online and in store","og_url":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T16:09:15+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/afw16.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/","url":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/","name":"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/afw16.jpg","datePublished":"2018-10-25T04:00:00+00:00","dateModified":"2022-04-18T16:09:15+00:00","description":"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade \u2013 more sizes available online and in store","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/afw16.jpg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/afw16.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/cars-and-boats\/wipers\/afw16-16-4-seasons-wiper-blade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"AFW16 \u2013 16 \u201d 4 Seasons Wiper Blade"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/101719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=101719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/68781"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=101719"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=101719"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=101719"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=101719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}