{"id":106206,"date":"2020-03-31T00:00:00","date_gmt":"2020-03-31T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/"},"modified":"2022-04-18T10:46:42","modified_gmt":"2022-04-18T14:46:42","slug":"wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/","title":{"rendered":"WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable"},"content":{"rendered":"<h2>WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable<\/h2>\n<div class=\"DHcWmd\">Security has never been easier<span style=\"font-family: Consolas,Monaco,monospace\">.<\/span><\/div>\n<h3>Description<\/h3>\n<p>With its flexible steel cable you can use it in several situation when a more traditional lock would not work. With its quick and easy opening you can remove the padlock with only one hand. Scratches will be minimized thanks to the vinyl coating<\/p>\n<h3>Features<\/h3>\n<ul>\n<li><span lang=\"en\">Up to 10,000 possible combinations resettable at any time <\/span><\/li>\n<li><span lang=\"en\">Cable 8mm thick and 5ft long<\/span><\/li>\n<li>Color: Blue<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable Security has never been easier. Description With its flexible steel cable you can use it in several situation when a more traditional lock would not work. With its quick and easy opening you can remove the padlock with only one hand. Scratches will be minimized thanks [&hellip;]<\/p>\n","protected":false},"featured_media":69777,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[14254,11550],"product_tag":[12525,12109],"class_list":["post-106206","product","type-product","status-publish","has-post-thumbnail","product_cat-hardware-en","product_cat-tools","product_tag-lock-en-2","product_tag-padlock","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":12,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable - Add-Tronique<\/title>\n<meta name=\"description\" content=\"WordLock CL-661-BL \u2013 5&#039; Steel Cable with Lock Flexible steel cable Resettable padlock\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"WordLock CL-661-BL \u2013 5&#039; Steel Cable with Lock Flexible steel cable Resettable padlock\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T14:46:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/cl-661.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1616\" \/>\n\t<meta property=\"og:image:height\" content=\"2016\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/hardware-en\\\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/hardware-en\\\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\\\/\",\"name\":\"WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/hardware-en\\\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/hardware-en\\\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cl-661.jpg\",\"datePublished\":\"2020-03-31T04:00:00+00:00\",\"dateModified\":\"2022-04-18T14:46:42+00:00\",\"description\":\"WordLock CL-661-BL \u2013 5' Steel Cable with Lock Flexible steel cable Resettable padlock\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/hardware-en\\\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/hardware-en\\\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/hardware-en\\\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cl-661.jpg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/cl-661.jpg\",\"width\":1616,\"height\":2016},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/tools\\\/hardware-en\\\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable - Add-Tronique","description":"WordLock CL-661-BL \u2013 5' Steel Cable with Lock Flexible steel cable Resettable padlock","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/","og_locale":"en_US","og_type":"article","og_title":"WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable - Add-Tronique","og_description":"WordLock CL-661-BL \u2013 5' Steel Cable with Lock Flexible steel cable Resettable padlock","og_url":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T14:46:42+00:00","og_image":[{"width":1616,"height":2016,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/cl-661.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/","url":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/","name":"WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/cl-661.jpg","datePublished":"2020-03-31T04:00:00+00:00","dateModified":"2022-04-18T14:46:42+00:00","description":"WordLock CL-661-BL \u2013 5' Steel Cable with Lock Flexible steel cable Resettable padlock","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/cl-661.jpg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/cl-661.jpg","width":1616,"height":2016},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/tools\/hardware-en\/wordlock-cl-661-bl-5-feet-resettable-flexible-steel-lock-cable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"WordLock CL-661-BL \u20135 Feet Resettable Flexible Steel Lock Cable"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/106206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=106206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/69777"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=106206"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=106206"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=106206"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=106206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}