{"id":106995,"date":"2020-01-06T00:00:00","date_gmt":"2020-01-06T05:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/"},"modified":"2022-04-18T11:23:12","modified_gmt":"2022-04-18T15:23:12","slug":"ge-35682-15-feet-series-pro-premium-hdmi-cable","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/","title":{"rendered":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable"},"content":{"rendered":"<h2>C\u00e2ble HDMI Pro Premium 15&#8242; \u2013 GE 35682<\/h2>\n<p>Le c\u00e2ble HDMI connecte facilement vos appareils tels que les t\u00e9l\u00e9viseurs, DVR , Blu- Ray , console de jeux et tout autre appareils avec un port HDMI.<\/p>\n<p>Le c\u00e2ble est certifi\u00e9 par le programme de certification HDMI Premium pour 4K UltraHD et le 18 Gbit offre des taux de rafra\u00eechissement fluides et rapides comme l&#8217;\u00e9clair et permet une visualisation transparente. Ce c\u00e2ble HDMI est compatible 3D et prend en charge une communication bidirectionnelle am\u00e9lior\u00e9e. Le c\u00e2ble HDMI GE Premium est r\u00e9sistant \u00e0 la corrosion avec des connexions plaqu\u00e9es or pour cr\u00e9er une connexion fiable<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e2ble HDMI Pro Premium 15&#8242; \u2013 GE 35682 Le c\u00e2ble HDMI connecte facilement vos appareils tels que les t\u00e9l\u00e9viseurs, DVR , Blu- Ray , console de jeux et tout autre appareils avec un port HDMI. Le c\u00e2ble est certifi\u00e9 par le programme de certification HDMI Premium pour 4K UltraHD et le 18 Gbit offre des [&hellip;]<\/p>\n","protected":false},"featured_media":110289,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11961,11089,11632,11103],"product_tag":[11684,11682],"class_list":["post-106995","product","type-product","status-publish","has-post-thumbnail","product_cat-brands-en","product_cat-cable","product_cat-ge","product_cat-hdmi-cable","product_tag-hdmi-en","product_tag-hdmi-cable-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":144,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - Add-Tronique<\/title>\n<meta name=\"description\" content=\"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - 4K 3D compatible and supports enhanced two-way communication\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - 4K 3D compatible and supports enhanced two-way communication\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T15:23:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/35682.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/ge\\\/ge-35682-15-feet-series-pro-premium-hdmi-cable\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/ge\\\/ge-35682-15-feet-series-pro-premium-hdmi-cable\\\/\",\"name\":\"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/ge\\\/ge-35682-15-feet-series-pro-premium-hdmi-cable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/ge\\\/ge-35682-15-feet-series-pro-premium-hdmi-cable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/35682.jpg\",\"datePublished\":\"2020-01-06T05:00:00+00:00\",\"dateModified\":\"2022-04-18T15:23:12+00:00\",\"description\":\"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - 4K 3D compatible and supports enhanced two-way communication\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/ge\\\/ge-35682-15-feet-series-pro-premium-hdmi-cable\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/ge\\\/ge-35682-15-feet-series-pro-premium-hdmi-cable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/ge\\\/ge-35682-15-feet-series-pro-premium-hdmi-cable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/35682.jpg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/35682.jpg\",\"width\":700,\"height\":700,\"caption\":\"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/ge\\\/ge-35682-15-feet-series-pro-premium-hdmi-cable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - Add-Tronique","description":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - 4K 3D compatible and supports enhanced two-way communication","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/","og_locale":"en_US","og_type":"article","og_title":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - Add-Tronique","og_description":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - 4K 3D compatible and supports enhanced two-way communication","og_url":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T15:23:12+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/35682.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/","url":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/","name":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/35682.jpg","datePublished":"2020-01-06T05:00:00+00:00","dateModified":"2022-04-18T15:23:12+00:00","description":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable - 4K 3D compatible and supports enhanced two-way communication","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/35682.jpg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/35682.jpg","width":700,"height":700,"caption":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable"},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/ge\/ge-35682-15-feet-series-pro-premium-hdmi-cable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"Ge 35682 \u2013 15 Feet Series Pro Premium HDMI Cable"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/106995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=106995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/110289"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=106995"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=106995"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=106995"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=106995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}