{"id":107692,"date":"2020-09-03T00:00:00","date_gmt":"2020-09-03T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/slow-blow-pack-of-5-6a-fuse\/"},"modified":"2022-04-18T10:21:12","modified_gmt":"2022-04-18T14:21:12","slug":"slow-blow-pack-of-5-6a-fuse","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/","title":{"rendered":"Slow Blow \u2013 Pack of 5 6A GMA Fuse"},"content":{"rendered":"<h2>Slow Blow \u2013 Pack of 5 6A GMA Fuse<\/h2>\n<ul>\n<li>6 A<\/li>\n<li>250 V<\/li>\n<li>Slow Blow<\/li>\n<li>Dimensions : 5 mm x 20 mm (0.197\u2033 x 0.769\u2033)<\/li>\n<li>Pack of 5<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Slow Blow \u2013 Pack of 5 6A GMA Fuse 6 A 250 V Slow Blow Dimensions : 5 mm x 20 mm (0.197\u2033 x 0.769\u2033) Pack of 5<\/p>\n","protected":false},"featured_media":113642,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11810,13425],"product_tag":[13137,13893,14317],"class_list":["post-107692","product","type-product","status-publish","has-post-thumbnail","product_cat-electricity","product_cat-gdl-fuse","product_tag-fuse-en","product_tag-fuse-en-2","product_tag-fuse-6a-en-2","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":4,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Slow Blow \u2013 Pack of 5 6A GMA Fuse - Add-Tronique<\/title>\n<meta name=\"description\" content=\"Slow Blow \u2013 Pack of 5 6A GDL Fuse \u2013 several fuse models available online and in store - Add-Tronique INC -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slow Blow \u2013 Pack of 5 6A GMA Fuse - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"Slow Blow \u2013 Pack of 5 6A GDL Fuse \u2013 several fuse models available online and in store - Add-Tronique INC -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T14:21:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/GDL-6A.png\" \/>\n\t<meta property=\"og:image:width\" content=\"506\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/gdl-fuse\\\/slow-blow-pack-of-5-6a-fuse\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/gdl-fuse\\\/slow-blow-pack-of-5-6a-fuse\\\/\",\"name\":\"Slow Blow \u2013 Pack of 5 6A GMA Fuse - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/gdl-fuse\\\/slow-blow-pack-of-5-6a-fuse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/gdl-fuse\\\/slow-blow-pack-of-5-6a-fuse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GDL-6A.png\",\"datePublished\":\"2020-09-03T04:00:00+00:00\",\"dateModified\":\"2022-04-18T14:21:12+00:00\",\"description\":\"Slow Blow \u2013 Pack of 5 6A GDL Fuse \u2013 several fuse models available online and in store - Add-Tronique INC -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/gdl-fuse\\\/slow-blow-pack-of-5-6a-fuse\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/gdl-fuse\\\/slow-blow-pack-of-5-6a-fuse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/gdl-fuse\\\/slow-blow-pack-of-5-6a-fuse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GDL-6A.png\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/GDL-6A.png\",\"width\":506,\"height\":502,\"caption\":\"Slow Blow \u2013 Pack of 5 6A GMA Fuse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/gdl-fuse\\\/slow-blow-pack-of-5-6a-fuse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slow Blow \u2013 Pack of 5 6A GMA Fuse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slow Blow \u2013 Pack of 5 6A GMA Fuse - Add-Tronique","description":"Slow Blow \u2013 Pack of 5 6A GDL Fuse \u2013 several fuse models available online and in store - Add-Tronique INC -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/","og_locale":"en_US","og_type":"article","og_title":"Slow Blow \u2013 Pack of 5 6A GMA Fuse - Add-Tronique","og_description":"Slow Blow \u2013 Pack of 5 6A GDL Fuse \u2013 several fuse models available online and in store - Add-Tronique INC -","og_url":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T14:21:12+00:00","og_image":[{"width":506,"height":502,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/GDL-6A.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/","url":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/","name":"Slow Blow \u2013 Pack of 5 6A GMA Fuse - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/GDL-6A.png","datePublished":"2020-09-03T04:00:00+00:00","dateModified":"2022-04-18T14:21:12+00:00","description":"Slow Blow \u2013 Pack of 5 6A GDL Fuse \u2013 several fuse models available online and in store - Add-Tronique INC -","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/GDL-6A.png","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/GDL-6A.png","width":506,"height":502,"caption":"Slow Blow \u2013 Pack of 5 6A GMA Fuse"},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/gdl-fuse\/slow-blow-pack-of-5-6a-fuse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"Slow Blow \u2013 Pack of 5 6A GMA Fuse"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/107692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=107692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/113642"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=107692"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=107692"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=107692"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=107692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}