{"id":112766,"date":"2022-03-31T12:13:05","date_gmt":"2022-03-31T16:13:05","guid":{"rendered":"https:\/\/add-tronique.com\/produit\/uncategorized\/pack-of-2-green-fuse-style-36-mm-3-led-light\/"},"modified":"2022-04-18T10:03:57","modified_gmt":"2022-04-18T14:03:57","slug":"pack-of-2-green-fuse-style-36-mm-3-led-light","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/","title":{"rendered":"Pack of 2 Green Fuse Style 36 mm 3 LED Light"},"content":{"rendered":"<h1 class=\"product_title featured-title entry-title\">Pack of 2 Green Fuse Style 36 mm 3 LED Light<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Pack of 2 Green Fuse Style 36 mm 3 LED Light<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11416],"product_tag":[13024,13026],"class_list":["post-112766","product","type-product","status-publish","product_cat-12vdc-led-light","product_tag-36-mm-led","product_tag-green-light","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":78,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pack of 2 Green Fuse Style 36 mm 3 LED Light - Add-Tronique<\/title>\n<meta name=\"description\" content=\"Pack of 2 Green Fuse Style 36 mm 3 LED Light \u2013 several models available in store or online \u2013 Add-Tronique INC\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pack of 2 Green Fuse Style 36 mm 3 LED Light - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"Pack of 2 Green Fuse Style 36 mm 3 LED Light \u2013 several models available in store or online \u2013 Add-Tronique INC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T14:03:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2022\/03\/U-DF36A-3S50-v.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/12vdc-led-light\\\/pack-of-2-green-fuse-style-36-mm-3-led-light\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/12vdc-led-light\\\/pack-of-2-green-fuse-style-36-mm-3-led-light\\\/\",\"name\":\"Pack of 2 Green Fuse Style 36 mm 3 LED Light - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"datePublished\":\"2022-03-31T16:13:05+00:00\",\"dateModified\":\"2022-04-18T14:03:57+00:00\",\"description\":\"Pack of 2 Green Fuse Style 36 mm 3 LED Light \u2013 several models available in store or online \u2013 Add-Tronique INC\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/12vdc-led-light\\\/pack-of-2-green-fuse-style-36-mm-3-led-light\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/12vdc-led-light\\\/pack-of-2-green-fuse-style-36-mm-3-led-light\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/12vdc-led-light\\\/pack-of-2-green-fuse-style-36-mm-3-led-light\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pack of 2 Green Fuse Style 36 mm 3 LED Light\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pack of 2 Green Fuse Style 36 mm 3 LED Light - Add-Tronique","description":"Pack of 2 Green Fuse Style 36 mm 3 LED Light \u2013 several models available in store or online \u2013 Add-Tronique INC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/","og_locale":"en_US","og_type":"article","og_title":"Pack of 2 Green Fuse Style 36 mm 3 LED Light - Add-Tronique","og_description":"Pack of 2 Green Fuse Style 36 mm 3 LED Light \u2013 several models available in store or online \u2013 Add-Tronique INC","og_url":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T14:03:57+00:00","og_image":[{"width":450,"height":450,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2022\/03\/U-DF36A-3S50-v.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/","url":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/","name":"Pack of 2 Green Fuse Style 36 mm 3 LED Light - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"datePublished":"2022-03-31T16:13:05+00:00","dateModified":"2022-04-18T14:03:57+00:00","description":"Pack of 2 Green Fuse Style 36 mm 3 LED Light \u2013 several models available in store or online \u2013 Add-Tronique INC","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/12vdc-led-light\/pack-of-2-green-fuse-style-36-mm-3-led-light\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"Pack of 2 Green Fuse Style 36 mm 3 LED Light"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/112766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=112766"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=112766"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=112766"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=112766"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=112766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}