{"id":98480,"date":"2018-10-03T00:00:00","date_gmt":"2018-10-03T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/8ft-heavy-duty-extension-cord\/"},"modified":"2022-04-18T12:46:38","modified_gmt":"2022-04-18T16:46:38","slug":"eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/","title":{"rendered":"ECLIPSE PRO AC-8 \u2013 8&#8242; 3\/16 Heavy Duty Extension Cord"},"content":{"rendered":"<h2>ECLIPSE PRO AC-8 \u2013 8&#8242; 3\/16 Heavy Duty Extension Cord<\/h2>\n<ul>\n<li>Polarised<\/li>\n<li>One outlet<\/li>\n<li>3-16 AWG<\/li>\n<li>8 Ft \/ 2.46 Meters<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>ECLIPSE PRO AC-8 \u2013 8&#8242; 3\/16 Heavy Duty Extension Cord Polarised One outlet 3-16 AWG 8 Ft \/ 2.46 Meters<\/p>\n","protected":false},"featured_media":65644,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11112],"product_tag":[12422,11811,12599],"class_list":["post-98480","product","type-product","status-publish","has-post-thumbnail","product_cat-ac-extension-cord","product_tag-electrical-extension","product_tag-extension-en","product_tag-extension-cord-en-2","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":13,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ECLIPSE PRO AC-8 \u2013 8&#039; 3\/16 Heavy Duty Extension Cord - Add-Tronique<\/title>\n<meta name=\"description\" content=\"ECLIPSE PRO AC-8 \u2013 8&#039; 3\/16 Heavy Duty Extension Cord \u2013 several extension models available online and in store\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ECLIPSE PRO AC-8 \u2013 8&#039; 3\/16 Heavy Duty Extension Cord - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"ECLIPSE PRO AC-8 \u2013 8&#039; 3\/16 Heavy Duty Extension Cord \u2013 several extension models available online and in store\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T16:46:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ac-8.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/ac-extension-cord\\\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/ac-extension-cord\\\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\\\/\",\"name\":\"ECLIPSE PRO AC-8 \u2013 8' 3\\\/16 Heavy Duty Extension Cord - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/ac-extension-cord\\\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/ac-extension-cord\\\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ac-8.jpeg\",\"datePublished\":\"2018-10-03T04:00:00+00:00\",\"dateModified\":\"2022-04-18T16:46:38+00:00\",\"description\":\"ECLIPSE PRO AC-8 \u2013 8' 3\\\/16 Heavy Duty Extension Cord \u2013 several extension models available online and in store\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/ac-extension-cord\\\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/ac-extension-cord\\\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/ac-extension-cord\\\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ac-8.jpeg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ac-8.jpeg\",\"width\":300,\"height\":300,\"caption\":\"ECLIPSE PRO AC-8 \u2013 8' 3\\\/16 Heavy Duty Extension Cord\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/electricity\\\/ac-extension-cord\\\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ECLIPSE PRO AC-8 \u2013 8&#8242; 3\\\/16 Heavy Duty Extension Cord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECLIPSE PRO AC-8 \u2013 8' 3\/16 Heavy Duty Extension Cord - Add-Tronique","description":"ECLIPSE PRO AC-8 \u2013 8' 3\/16 Heavy Duty Extension Cord \u2013 several extension models available online and in store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/","og_locale":"en_US","og_type":"article","og_title":"ECLIPSE PRO AC-8 \u2013 8' 3\/16 Heavy Duty Extension Cord - Add-Tronique","og_description":"ECLIPSE PRO AC-8 \u2013 8' 3\/16 Heavy Duty Extension Cord \u2013 several extension models available online and in store","og_url":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T16:46:38+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ac-8.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/","url":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/","name":"ECLIPSE PRO AC-8 \u2013 8' 3\/16 Heavy Duty Extension Cord - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ac-8.jpeg","datePublished":"2018-10-03T04:00:00+00:00","dateModified":"2022-04-18T16:46:38+00:00","description":"ECLIPSE PRO AC-8 \u2013 8' 3\/16 Heavy Duty Extension Cord \u2013 several extension models available online and in store","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ac-8.jpeg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ac-8.jpeg","width":300,"height":300,"caption":"ECLIPSE PRO AC-8 \u2013 8' 3\/16 Heavy Duty Extension Cord"},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/electricity\/ac-extension-cord\/eclipse-pro-ac-8-8-3-16-heavy-duty-extension-cord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"ECLIPSE PRO AC-8 \u2013 8&#8242; 3\/16 Heavy Duty Extension Cord"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/98480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=98480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/65644"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=98480"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=98480"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=98480"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=98480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}