{"id":98484,"date":"2018-10-03T00:00:00","date_gmt":"2018-10-03T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/male-displayport-to-female-vga-adapter\/"},"modified":"2022-04-18T12:46:35","modified_gmt":"2022-04-18T16:46:35","slug":"male-displayport-to-female-vga-adapter","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/","title":{"rendered":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter"},"content":{"rendered":"<h2>ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter<\/h2>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Traduction\"><span class=\"Y2IQFc\" lang=\"en\">The DisplayPort male to VGA female adapter allows you to connect an external monitor equipped with a VGA input.<\/span><\/p>\n<ul>\n<li><span class=\"Y2IQFc\" lang=\"en\">DisplayPort male to VGA female cable<\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"en\">15-pin DislayPort input<br \/>\n<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter The DisplayPort male to VGA female adapter allows you to connect an external monitor equipped with a VGA input. DisplayPort male to VGA female cable 15-pin DislayPort input<\/p>\n","protected":false},"featured_media":67645,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11090],"product_tag":[12603,12602,12604],"class_list":["post-98484","product","type-product","status-publish","has-post-thumbnail","product_cat-monitor-cable","product_tag-display-port-en","product_tag-display-port-adapter","product_tag-dp-to-vga","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":5,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter -<\/title>\n<meta name=\"description\" content=\"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter -\" \/>\n<meta property=\"og:description\" content=\"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T16:46:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ada-dp-vga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cable\\\/monitor-cable\\\/male-displayport-to-female-vga-adapter\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cable\\\/monitor-cable\\\/male-displayport-to-female-vga-adapter\\\/\",\"name\":\"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cable\\\/monitor-cable\\\/male-displayport-to-female-vga-adapter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cable\\\/monitor-cable\\\/male-displayport-to-female-vga-adapter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ada-dp-vga.jpg\",\"datePublished\":\"2018-10-03T04:00:00+00:00\",\"dateModified\":\"2022-04-18T16:46:35+00:00\",\"description\":\"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cable\\\/monitor-cable\\\/male-displayport-to-female-vga-adapter\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cable\\\/monitor-cable\\\/male-displayport-to-female-vga-adapter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cable\\\/monitor-cable\\\/male-displayport-to-female-vga-adapter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ada-dp-vga.jpg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ada-dp-vga.jpg\",\"width\":300,\"height\":300,\"caption\":\"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/cable\\\/monitor-cable\\\/male-displayport-to-female-vga-adapter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter -","description":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/","og_locale":"en_US","og_type":"article","og_title":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter -","og_description":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter","og_url":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T16:46:35+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ada-dp-vga.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/","url":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/","name":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter -","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ada-dp-vga.jpg","datePublished":"2018-10-03T04:00:00+00:00","dateModified":"2022-04-18T16:46:35+00:00","description":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ada-dp-vga.jpg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/ada-dp-vga.jpg","width":300,"height":300,"caption":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter"},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/cable\/monitor-cable\/male-displayport-to-female-vga-adapter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"ADA-DP-VGA \u2013 Male Displayport to Female VGA Adapter"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/98484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=98484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/67645"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=98484"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=98484"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=98484"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=98484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}