{"id":98832,"date":"2018-10-03T00:00:00","date_gmt":"2018-10-03T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/inline-xlr-f-to-xlr-f-adapter\/"},"modified":"2022-05-16T14:16:38","modified_gmt":"2022-05-16T18:16:38","slug":"neutrik-na3ff-3-pole-xlr-female-adapter","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/","title":{"rendered":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter"},"content":{"rendered":"<h2>Neutrik NA3FF \u2013 3 pole XLR Female Adapter<\/h2>\n<p>Versatile, pre-wired and ready to use adapters to reliably interlock various connector systems<\/p>\n<ul>\n<li>Professional look and compact space saving design, based on the XX Series<\/li>\n<li>Rugged diecast shell for best reliability<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Neutrik NA3FF \u2013 3 pole XLR Female Adapter Versatile, pre-wired and ready to use adapters to reliably interlock various connector systems Professional look and compact space saving design, based on the XX Series Rugged diecast shell for best reliability<\/p>\n","protected":false},"featured_media":66038,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[12333,13646],"product_tag":[13650,12337,13649],"class_list":["post-98832","product","type-product","status-publish","has-post-thumbnail","product_cat-neutrik-en","product_cat-xlr-connector","product_tag-female-xlr-en","product_tag-xlr-en","product_tag-xlr-adapter","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":3,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neutrik NA3FF \u2013 3 pole XLR Female Adapter - Add-Tronique<\/title>\n<meta name=\"description\" content=\"Neutrik NA3FF \u2013 3 pole XLR Female Adapter \u2013 pre-wired and ready to use adapters to reliably interlock various connector systems\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neutrik NA3FF \u2013 3 pole XLR Female Adapter - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"Neutrik NA3FF \u2013 3 pole XLR Female Adapter \u2013 pre-wired and ready to use adapters to reliably interlock various connector systems\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-16T18:16:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/NA3FF.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/neutrik-en\\\/neutrik-na3ff-3-pole-xlr-female-adapter\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/neutrik-en\\\/neutrik-na3ff-3-pole-xlr-female-adapter\\\/\",\"name\":\"Neutrik NA3FF \u2013 3 pole XLR Female Adapter - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/neutrik-en\\\/neutrik-na3ff-3-pole-xlr-female-adapter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/neutrik-en\\\/neutrik-na3ff-3-pole-xlr-female-adapter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/NA3FF.jpg\",\"datePublished\":\"2018-10-03T04:00:00+00:00\",\"dateModified\":\"2022-05-16T18:16:38+00:00\",\"description\":\"Neutrik NA3FF \u2013 3 pole XLR Female Adapter \u2013 pre-wired and ready to use adapters to reliably interlock various connector systems\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/neutrik-en\\\/neutrik-na3ff-3-pole-xlr-female-adapter\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/neutrik-en\\\/neutrik-na3ff-3-pole-xlr-female-adapter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/neutrik-en\\\/neutrik-na3ff-3-pole-xlr-female-adapter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/NA3FF.jpg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/NA3FF.jpg\",\"width\":300,\"height\":300,\"caption\":\"Neutrik NA3FF \u2013 3 pole XLR Female Adapter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/neutrik-en\\\/neutrik-na3ff-3-pole-xlr-female-adapter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neutrik NA3FF \u2013 3 pole XLR Female Adapter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter - Add-Tronique","description":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter \u2013 pre-wired and ready to use adapters to reliably interlock various connector systems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/","og_locale":"en_US","og_type":"article","og_title":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter - Add-Tronique","og_description":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter \u2013 pre-wired and ready to use adapters to reliably interlock various connector systems","og_url":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/","og_site_name":"Add-Tronique","article_modified_time":"2022-05-16T18:16:38+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/NA3FF.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/","url":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/","name":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/NA3FF.jpg","datePublished":"2018-10-03T04:00:00+00:00","dateModified":"2022-05-16T18:16:38+00:00","description":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter \u2013 pre-wired and ready to use adapters to reliably interlock various connector systems","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/NA3FF.jpg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/NA3FF.jpg","width":300,"height":300,"caption":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter"},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/neutrik-en\/neutrik-na3ff-3-pole-xlr-female-adapter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"Neutrik NA3FF \u2013 3 pole XLR Female Adapter"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/98832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=98832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/66038"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=98832"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=98832"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=98832"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=98832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}