{"id":99403,"date":"2020-09-30T00:00:00","date_gmt":"2020-09-30T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/halogen-t3-j-type-300w-bulb\/"},"modified":"2022-04-18T10:18:11","modified_gmt":"2022-04-18T14:18:11","slug":"halogen-t3-j-type-300w-bulb","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/","title":{"rendered":"Halogen T3 J-Type \/ 300W Bulb"},"content":{"rendered":"<h2>Ampoule halog\u00e8ne T3 J-Type \/ 300W Xtricity 1-62034<\/h2>\n<ul>\n<li>Type: T3 J<\/li>\n<li>Wattage: 300 w<\/li>\n<li>Couleur: Claire<\/li>\n<li>Flux lumineux: 4505 lumens<\/li>\n<li>Culot: RSC \u00e0 double contact<\/li>\n<li>Temp\u00e9rature de couleur: 2700 K &#8211; blanc doux<\/li>\n<li>\u00c9tendue du faisceau: N\/A<\/li>\n<li>Graduelle: oui<\/li>\n<li>Voltage: 130V<\/li>\n<li>Dur\u00e9e de vie: 1500 hrs<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ampoule halog\u00e8ne T3 J-Type \/ 300W Xtricity 1-62034 Type: T3 J Wattage: 300 w Couleur: Claire Flux lumineux: 4505 lumens Culot: RSC \u00e0 double contact Temp\u00e9rature de couleur: 2700 K &#8211; blanc doux \u00c9tendue du faisceau: N\/A Graduelle: oui Voltage: 130V Dur\u00e9e de vie: 1500 hrs &nbsp;<\/p>\n","protected":false},"featured_media":68297,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[14453],"product_tag":[12133],"class_list":["post-99403","product","type-product","status-publish","has-post-thumbnail","product_cat-lightings","product_tag-bulb-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":7,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Halogen T3 J-Type \/ 300W Bulb - Add-Tronique<\/title>\n<meta name=\"description\" content=\"Halogen T3 J-Type \/ 300W Bulb \u2013 Brightness: 4505 lumens \u2013 Rated life 1500 hours\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Halogen T3 J-Type \/ 300W Bulb - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"Halogen T3 J-Type \/ 300W Bulb \u2013 Brightness: 4505 lumens \u2013 Rated life 1500 hours\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T14:18:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/1-62034-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/halogen-t3-j-type-300w-bulb\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/halogen-t3-j-type-300w-bulb\\\/\",\"name\":\"Halogen T3 J-Type \\\/ 300W Bulb - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/halogen-t3-j-type-300w-bulb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/halogen-t3-j-type-300w-bulb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/1-62034-1.jpg\",\"datePublished\":\"2020-09-30T04:00:00+00:00\",\"dateModified\":\"2022-04-18T14:18:11+00:00\",\"description\":\"Halogen T3 J-Type \\\/ 300W Bulb \u2013 Brightness: 4505 lumens \u2013 Rated life 1500 hours\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/halogen-t3-j-type-300w-bulb\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/halogen-t3-j-type-300w-bulb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/halogen-t3-j-type-300w-bulb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/1-62034-1.jpg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/1-62034-1.jpg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/lightings\\\/halogen-t3-j-type-300w-bulb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Halogen T3 J-Type \\\/ 300W Bulb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Halogen T3 J-Type \/ 300W Bulb - Add-Tronique","description":"Halogen T3 J-Type \/ 300W Bulb \u2013 Brightness: 4505 lumens \u2013 Rated life 1500 hours","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/","og_locale":"en_US","og_type":"article","og_title":"Halogen T3 J-Type \/ 300W Bulb - Add-Tronique","og_description":"Halogen T3 J-Type \/ 300W Bulb \u2013 Brightness: 4505 lumens \u2013 Rated life 1500 hours","og_url":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T14:18:11+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/1-62034-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/","url":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/","name":"Halogen T3 J-Type \/ 300W Bulb - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/1-62034-1.jpg","datePublished":"2020-09-30T04:00:00+00:00","dateModified":"2022-04-18T14:18:11+00:00","description":"Halogen T3 J-Type \/ 300W Bulb \u2013 Brightness: 4505 lumens \u2013 Rated life 1500 hours","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/1-62034-1.jpg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/1-62034-1.jpg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/lightings\/halogen-t3-j-type-300w-bulb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"Halogen T3 J-Type \/ 300W Bulb"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/99403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=99403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/68297"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=99403"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=99403"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=99403"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=99403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}