{"id":99867,"date":"2020-02-11T00:00:00","date_gmt":"2018-10-25T04:00:00","guid":{"rendered":"https:\/\/addtronique.com\/produit\/non%20class\u00e9\/iit-24590-8-multi-purpose-metal-snip\/"},"modified":"2022-04-18T11:09:50","modified_gmt":"2022-04-18T15:09:50","slug":"iit-24590-8-multi-purpose-metal-snip","status":"publish","type":"product","link":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/","title":{"rendered":"IIT 24590 \u2013 8&#8243; Multi-Purpose Metal Snip"},"content":{"rendered":"<h2>IIT 24590 \u2013 8&#8243; Multi-Purpose Metal Snip<\/h2>\n<ul>\n<li>Quickly and easily cuts thin gauge sheet metal and wire<br \/>\nInnovative spring washer holds the blades tightly together for an accurate cut all the way to the tip<\/li>\n<li>Use on a variety of material like upholstery, plastic, heavy fabric and denim<\/li>\n<li>Durable blades stay sharpe longer<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>IIT 24590 \u2013 8&#8243; Multi-Purpose Metal Snip Quickly and easily cuts thin gauge sheet metal and wire Innovative spring washer holds the blades tightly together for an accurate cut all the way to the tip Use on a variety of material like upholstery, plastic, heavy fabric and denim Durable blades stay sharpe longer<\/p>\n","protected":false},"featured_media":68465,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[11961,12090,11581,11550],"product_tag":[11917],"class_list":["post-99867","product","type-product","status-publish","has-post-thumbnail","product_cat-brands-en","product_cat-iit","product_cat-pliers","product_cat-tools","product_tag-pliers-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":2,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IIT 24590 \u2013 8&quot; Multi-Purpose Metal Snip - Add-Tronique<\/title>\n<meta name=\"description\" content=\"IIT 24590 \u2013 8&quot; Multi-Purpose Metal Snip Quickly and easily cuts thin gauge sheet metal and wire\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IIT 24590 \u2013 8&quot; Multi-Purpose Metal Snip - Add-Tronique\" \/>\n<meta property=\"og:description\" content=\"IIT 24590 \u2013 8&quot; Multi-Purpose Metal Snip Quickly and easily cuts thin gauge sheet metal and wire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/\" \/>\n<meta property=\"og:site_name\" content=\"Add-Tronique\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T15:09:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/24590.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/iit\\\/iit-24590-8-multi-purpose-metal-snip\\\/\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/iit\\\/iit-24590-8-multi-purpose-metal-snip\\\/\",\"name\":\"IIT 24590 \u2013 8\\\" Multi-Purpose Metal Snip - Add-Tronique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/iit\\\/iit-24590-8-multi-purpose-metal-snip\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/iit\\\/iit-24590-8-multi-purpose-metal-snip\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/24590.jpg\",\"datePublished\":\"2018-10-25T04:00:00+00:00\",\"dateModified\":\"2022-04-18T15:09:50+00:00\",\"description\":\"IIT 24590 \u2013 8\\\" Multi-Purpose Metal Snip Quickly and easily cuts thin gauge sheet metal and wire\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/iit\\\/iit-24590-8-multi-purpose-metal-snip\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/iit\\\/iit-24590-8-multi-purpose-metal-snip\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/iit\\\/iit-24590-8-multi-purpose-metal-snip\\\/#primaryimage\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/24590.jpg\",\"contentUrl\":\"https:\\\/\\\/add-tronique.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/24590.jpg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/boutique\\\/brands-en\\\/iit\\\/iit-24590-8-multi-purpose-metal-snip\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IIT 24590 \u2013 8&#8243; Multi-Purpose Metal Snip\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/\",\"name\":\"Add-Tronique\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/add-tronique.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IIT 24590 \u2013 8\" Multi-Purpose Metal Snip - Add-Tronique","description":"IIT 24590 \u2013 8\" Multi-Purpose Metal Snip Quickly and easily cuts thin gauge sheet metal and wire","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/","og_locale":"en_US","og_type":"article","og_title":"IIT 24590 \u2013 8\" Multi-Purpose Metal Snip - Add-Tronique","og_description":"IIT 24590 \u2013 8\" Multi-Purpose Metal Snip Quickly and easily cuts thin gauge sheet metal and wire","og_url":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/","og_site_name":"Add-Tronique","article_modified_time":"2022-04-18T15:09:50+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/24590.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/","url":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/","name":"IIT 24590 \u2013 8\" Multi-Purpose Metal Snip - Add-Tronique","isPartOf":{"@id":"https:\/\/add-tronique.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/#primaryimage"},"image":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/#primaryimage"},"thumbnailUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/24590.jpg","datePublished":"2018-10-25T04:00:00+00:00","dateModified":"2022-04-18T15:09:50+00:00","description":"IIT 24590 \u2013 8\" Multi-Purpose Metal Snip Quickly and easily cuts thin gauge sheet metal and wire","breadcrumb":{"@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/#primaryimage","url":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/24590.jpg","contentUrl":"https:\/\/add-tronique.com\/wp-content\/uploads\/2021\/03\/24590.jpg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/add-tronique.com\/en\/boutique\/brands-en\/iit\/iit-24590-8-multi-purpose-metal-snip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/add-tronique.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"IIT 24590 \u2013 8&#8243; Multi-Purpose Metal Snip"}]},{"@type":"WebSite","@id":"https:\/\/add-tronique.com\/en\/#website","url":"https:\/\/add-tronique.com\/en\/","name":"Add-Tronique","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/add-tronique.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product\/99867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/comments?post=99867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media\/68465"}],"wp:attachment":[{"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/media?parent=99867"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_brand?post=99867"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_cat?post=99867"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/add-tronique.com\/en\/wp-json\/wp\/v2\/product_tag?post=99867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}